{"id":493,"count":0,"description":"","link":"https:\/\/prima2.sviluppo.host\/es\/categoria-producto\/m-juntas-para-vapor-y-seco\/juntas-seco-en-metros\/","name":"Juntas seco en metros","slug":"juntas-seco-en-metros","taxonomy":"product_cat","parent":491,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/prima2.sviluppo.host\/es\/wp-json\/wp\/v2\/product_cat\/493"}],"collection":[{"href":"https:\/\/prima2.sviluppo.host\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/prima2.sviluppo.host\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/prima2.sviluppo.host\/es\/wp-json\/wp\/v2\/product_cat\/491"}],"wp:post_type":[{"href":"https:\/\/prima2.sviluppo.host\/es\/wp-json\/wp\/v2\/product?product_cat=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}